{"id":19848,"date":"2021-07-26T11:54:42","date_gmt":"2021-07-26T11:54:42","guid":{"rendered":"https:\/\/mezquitadesevilla.com\/distribution-of-lambs-eid-al-adha-2021\/"},"modified":"2024-09-18T16:13:40","modified_gmt":"2024-09-18T16:13:40","slug":"distribution-of-lambs-eid-al-adha-2021","status":"publish","type":"post","link":"https:\/\/mezquitadesevilla.com\/en\/distribution-of-lambs-eid-al-adha-2021\/","title":{"rendered":"Distribution of lambs, Eid Al Adha 2021"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">The Seville Mosque Foundation has had the honor of distributing 14 lambs among 56 families in Seville on the occasion of Eid al Adha.\nThis assistance was made possible thanks to the Tirmidhi Foundation of Malaysia, and local contributions. <\/p>\n\n<p class=\"wp-block-paragraph\">Generosity is an essential part of Islam and one of the signs of those who have a heart of gratitude to Allah.\nThe Messenger, peace be upon him said, in a Hadith transmitted by Abu Hurairah: <\/p>\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>Generosity is close to Allah, close to Paradise, close to people and far from Hell.\nGreed is far from Allah, far from Paradise, far from people and close to Hellfire.\nA generous and ignorant person is more beloved to Allah, Exalted is He, than a mean scholar.\n(Tirmidhi)   <\/p><\/blockquote>\n\n<p class=\"wp-block-paragraph\">Part of being grateful to Allah is to be grateful to people, as the Prophet also reminded us in a Hadith (Ahmad, Tirmdhi), so we want to show our gratitude to the Tirmidhi Foundation as well as to all the people who have made this possible.  <\/p>\n\n<p class=\"wp-block-paragraph\">May Allah reward and accept the sacrifice to all who have made this possible.\nAmin. <\/p>\n\n<p class=\"wp-block-paragraph\"><br\/><\/p>\n\n<div class=\"wp-block-jetpack-tiled-gallery aligncenter is-style-rectangular\"><div class=\"tiled-gallery__gallery\"><div class=\"tiled-gallery__row\"><div class=\"tiled-gallery__col\" style=\"flex-basis:37.34430%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" role=\"button\" tabindex=\"0\" aria-label=\"Open image 1 of 14 in full-screen\" srcset=\"https:\/\/i1.wp.com\/mezquitadesevilla.com\/wp-content\/uploads\/2021\/07\/CBEID.jpg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i1.wp.com\/mezquitadesevilla.com\/wp-content\/uploads\/2021\/07\/CBEID.jpg?strip=info&#038;w=900&#038;ssl=1 900w,https:\/\/i1.wp.com\/mezquitadesevilla.com\/wp-content\/uploads\/2021\/07\/CBEID.jpg?strip=info&#038;w=1200&#038;ssl=1 1200w,https:\/\/i1.wp.com\/mezquitadesevilla.com\/wp-content\/uploads\/2021\/07\/CBEID.jpg?strip=info&#038;w=1375&#038;ssl=1 1375w\" alt=\"\" data-height=\"688\" data-id=\"14838\" data-link=\"https:\/\/mezquitadesevilla.com\/distribucion-de-corderos-eid-al-adha-2\/cbeid\/\" data-url=\"https:\/\/mezquitadesevilla.com\/wp-content\/uploads\/2021\/07\/CBEID.jpg\" data-width=\"1375\" src=\"https:\/\/i1.wp.com\/mezquitadesevilla.com\/wp-content\/uploads\/2021\/07\/CBEID.jpg?ssl=1\" data-amp-layout=\"responsive\"><\/figure><figure class=\"tiled-gallery__item\"><img decoding=\"async\" role=\"button\" tabindex=\"0\" aria-label=\"Open image 2 of 14 in full-screen\" srcset=\"https:\/\/i2.wp.com\/mezquitadesevilla.com\/wp-content\/uploads\/2021\/07\/IMG_4704-scaled.jpeg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i2.wp.com\/mezquitadesevilla.com\/wp-content\/uploads\/2021\/07\/IMG_4704-scaled.jpeg?strip=info&#038;w=900&#038;ssl=1 900w,https:\/\/i2.wp.com\/mezquitadesevilla.com\/wp-content\/uploads\/2021\/07\/IMG_4704-scaled.jpeg?strip=info&#038;w=1200&#038;ssl=1 1200w,https:\/\/i2.wp.com\/mezquitadesevilla.com\/wp-content\/uploads\/2021\/07\/IMG_4704-scaled.jpeg?strip=info&#038;w=1500&#038;ssl=1 1500w,https:\/\/i2.wp.com\/mezquitadesevilla.com\/wp-content\/uploads\/2021\/07\/IMG_4704-scaled.jpeg?strip=info&#038;w=1800&#038;ssl=1 1800w,https:\/\/i2.wp.com\/mezquitadesevilla.com\/wp-content\/uploads\/2021\/07\/IMG_4704-scaled.jpeg?strip=info&#038;w=2000&#038;ssl=1 2000w\" alt=\"\" data-height=\"1920\" data-id=\"14833\" data-link=\"https:\/\/mezquitadesevilla.com\/distribucion-de-corderos-eid-al-adha-2\/img_4704\/\" data-url=\"https:\/\/mezquitadesevilla.com\/wp-content\/uploads\/2021\/07\/IMG_4704-scaled.jpeg\" data-width=\"2560\" src=\"https:\/\/i2.wp.com\/mezquitadesevilla.com\/wp-content\/uploads\/2021\/07\/IMG_4704-scaled.jpeg?ssl=1\" data-amp-layout=\"responsive\"><\/figure><\/div><div class=\"tiled-gallery__col\" style=\"flex-basis:62.65570%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" role=\"button\" tabindex=\"0\" aria-label=\"Open image 3 of 14 in full-screen\" srcset=\"https:\/\/i1.wp.com\/mezquitadesevilla.com\/wp-content\/uploads\/2021\/07\/IMG_4651-scaled.jpeg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i1.wp.com\/mezquitadesevilla.com\/wp-content\/uploads\/2021\/07\/IMG_4651-scaled.jpeg?strip=info&#038;w=900&#038;ssl=1 900w,https:\/\/i1.wp.com\/mezquitadesevilla.com\/wp-content\/uploads\/2021\/07\/IMG_4651-scaled.jpeg?strip=info&#038;w=1200&#038;ssl=1 1200w,https:\/\/i1.wp.com\/mezquitadesevilla.com\/wp-content\/uploads\/2021\/07\/IMG_4651-scaled.jpeg?strip=info&#038;w=1500&#038;ssl=1 1500w,https:\/\/i1.wp.com\/mezquitadesevilla.com\/wp-content\/uploads\/2021\/07\/IMG_4651-scaled.jpeg?strip=info&#038;w=1800&#038;ssl=1 1800w,https:\/\/i1.wp.com\/mezquitadesevilla.com\/wp-content\/uploads\/2021\/07\/IMG_4651-scaled.jpeg?strip=info&#038;w=2000&#038;ssl=1 2000w\" alt=\"\" data-height=\"1920\" data-id=\"14831\" data-link=\"https:\/\/mezquitadesevilla.com\/distribucion-de-corderos-eid-al-adha-2\/img_4651\/\" data-url=\"https:\/\/mezquitadesevilla.com\/wp-content\/uploads\/2021\/07\/IMG_4651-scaled.jpeg\" data-width=\"2560\" src=\"https:\/\/i1.wp.com\/mezquitadesevilla.com\/wp-content\/uploads\/2021\/07\/IMG_4651-scaled.jpeg?ssl=1\" data-amp-layout=\"responsive\"><\/figure><\/div><\/div><div class=\"tiled-gallery__row\"><div class=\"tiled-gallery__col\" style=\"flex-basis:63.73910%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" role=\"button\" tabindex=\"0\" aria-label=\"Open image 4 of 14 in full-screen\" srcset=\"https:\/\/i1.wp.com\/mezquitadesevilla.com\/wp-content\/uploads\/2021\/07\/IMG_4676-scaled.jpeg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i1.wp.com\/mezquitadesevilla.com\/wp-content\/uploads\/2021\/07\/IMG_4676-scaled.jpeg?strip=info&#038;w=900&#038;ssl=1 900w,https:\/\/i1.wp.com\/mezquitadesevilla.com\/wp-content\/uploads\/2021\/07\/IMG_4676-scaled.jpeg?strip=info&#038;w=1200&#038;ssl=1 1200w,https:\/\/i1.wp.com\/mezquitadesevilla.com\/wp-content\/uploads\/2021\/07\/IMG_4676-scaled.jpeg?strip=info&#038;w=1500&#038;ssl=1 1500w,https:\/\/i1.wp.com\/mezquitadesevilla.com\/wp-content\/uploads\/2021\/07\/IMG_4676-scaled.jpeg?strip=info&#038;w=1800&#038;ssl=1 1800w,https:\/\/i1.wp.com\/mezquitadesevilla.com\/wp-content\/uploads\/2021\/07\/IMG_4676-scaled.jpeg?strip=info&#038;w=2000&#038;ssl=1 2000w\" alt=\"\" data-height=\"2560\" data-id=\"14819\" data-link=\"https:\/\/mezquitadesevilla.com\/distribucion-de-corderos-eid-al-adha-2\/img_4676\/\" data-url=\"https:\/\/mezquitadesevilla.com\/wp-content\/uploads\/2021\/07\/IMG_4676-scaled.jpeg\" data-width=\"2560\" src=\"https:\/\/i1.wp.com\/mezquitadesevilla.com\/wp-content\/uploads\/2021\/07\/IMG_4676-scaled.jpeg?ssl=1\" data-amp-layout=\"responsive\"><\/figure><\/div><div class=\"tiled-gallery__col\" style=\"flex-basis:36.26090%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" role=\"button\" tabindex=\"0\" aria-label=\"Open image 5 of 14 in full-screen\" srcset=\"https:\/\/i2.wp.com\/mezquitadesevilla.com\/wp-content\/uploads\/2021\/07\/IMG_4670-scaled.jpeg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i2.wp.com\/mezquitadesevilla.com\/wp-content\/uploads\/2021\/07\/IMG_4670-scaled.jpeg?strip=info&#038;w=900&#038;ssl=1 900w,https:\/\/i2.wp.com\/mezquitadesevilla.com\/wp-content\/uploads\/2021\/07\/IMG_4670-scaled.jpeg?strip=info&#038;w=1200&#038;ssl=1 1200w,https:\/\/i2.wp.com\/mezquitadesevilla.com\/wp-content\/uploads\/2021\/07\/IMG_4670-scaled.jpeg?strip=info&#038;w=1500&#038;ssl=1 1500w,https:\/\/i2.wp.com\/mezquitadesevilla.com\/wp-content\/uploads\/2021\/07\/IMG_4670-scaled.jpeg?strip=info&#038;w=1800&#038;ssl=1 1800w,https:\/\/i2.wp.com\/mezquitadesevilla.com\/wp-content\/uploads\/2021\/07\/IMG_4670-scaled.jpeg?strip=info&#038;w=2000&#038;ssl=1 2000w\" alt=\"\" data-height=\"2560\" data-id=\"14821\" data-link=\"https:\/\/mezquitadesevilla.com\/distribucion-de-corderos-eid-al-adha-2\/img_4670\/\" data-url=\"https:\/\/mezquitadesevilla.com\/wp-content\/uploads\/2021\/07\/IMG_4670-scaled.jpeg\" data-width=\"2560\" src=\"https:\/\/i2.wp.com\/mezquitadesevilla.com\/wp-content\/uploads\/2021\/07\/IMG_4670-scaled.jpeg?ssl=1\" data-amp-layout=\"responsive\"><\/figure><figure class=\"tiled-gallery__item\"><img decoding=\"async\" role=\"button\" tabindex=\"0\" aria-label=\"Open image 6 of 14 in full-screen\" srcset=\"https:\/\/i2.wp.com\/mezquitadesevilla.com\/wp-content\/uploads\/2021\/07\/IMG_4660-scaled.jpeg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i2.wp.com\/mezquitadesevilla.com\/wp-content\/uploads\/2021\/07\/IMG_4660-scaled.jpeg?strip=info&#038;w=900&#038;ssl=1 900w,https:\/\/i2.wp.com\/mezquitadesevilla.com\/wp-content\/uploads\/2021\/07\/IMG_4660-scaled.jpeg?strip=info&#038;w=1200&#038;ssl=1 1200w,https:\/\/i2.wp.com\/mezquitadesevilla.com\/wp-content\/uploads\/2021\/07\/IMG_4660-scaled.jpeg?strip=info&#038;w=1500&#038;ssl=1 1500w,https:\/\/i2.wp.com\/mezquitadesevilla.com\/wp-content\/uploads\/2021\/07\/IMG_4660-scaled.jpeg?strip=info&#038;w=1800&#038;ssl=1 1800w,https:\/\/i2.wp.com\/mezquitadesevilla.com\/wp-content\/uploads\/2021\/07\/IMG_4660-scaled.jpeg?strip=info&#038;w=2000&#038;ssl=1 2000w\" alt=\"\" data-height=\"1920\" data-id=\"14825\" data-link=\"https:\/\/mezquitadesevilla.com\/distribucion-de-corderos-eid-al-adha-2\/img_4660\/\" data-url=\"https:\/\/mezquitadesevilla.com\/wp-content\/uploads\/2021\/07\/IMG_4660-scaled.jpeg\" data-width=\"2560\" src=\"https:\/\/i2.wp.com\/mezquitadesevilla.com\/wp-content\/uploads\/2021\/07\/IMG_4660-scaled.jpeg?ssl=1\" data-amp-layout=\"responsive\"><\/figure><\/div><\/div><div class=\"tiled-gallery__row\"><div class=\"tiled-gallery__col\" style=\"flex-basis:33.33333%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" role=\"button\" tabindex=\"0\" aria-label=\"Open image 7 of 14 in full-screen\" srcset=\"https:\/\/i0.wp.com\/mezquitadesevilla.com\/wp-content\/uploads\/2021\/07\/IMG_4663-scaled.jpeg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i0.wp.com\/mezquitadesevilla.com\/wp-content\/uploads\/2021\/07\/IMG_4663-scaled.jpeg?strip=info&#038;w=900&#038;ssl=1 900w,https:\/\/i0.wp.com\/mezquitadesevilla.com\/wp-content\/uploads\/2021\/07\/IMG_4663-scaled.jpeg?strip=info&#038;w=1200&#038;ssl=1 1200w,https:\/\/i0.wp.com\/mezquitadesevilla.com\/wp-content\/uploads\/2021\/07\/IMG_4663-scaled.jpeg?strip=info&#038;w=1500&#038;ssl=1 1500w,https:\/\/i0.wp.com\/mezquitadesevilla.com\/wp-content\/uploads\/2021\/07\/IMG_4663-scaled.jpeg?strip=info&#038;w=1800&#038;ssl=1 1800w,https:\/\/i0.wp.com\/mezquitadesevilla.com\/wp-content\/uploads\/2021\/07\/IMG_4663-scaled.jpeg?strip=info&#038;w=2000&#038;ssl=1 2000w\" alt=\"\" data-height=\"1920\" data-id=\"14823\" data-link=\"https:\/\/mezquitadesevilla.com\/distribucion-de-corderos-eid-al-adha-2\/img_4663\/\" data-url=\"https:\/\/mezquitadesevilla.com\/wp-content\/uploads\/2021\/07\/IMG_4663-scaled.jpeg\" data-width=\"2560\" src=\"https:\/\/i0.wp.com\/mezquitadesevilla.com\/wp-content\/uploads\/2021\/07\/IMG_4663-scaled.jpeg?ssl=1\" data-amp-layout=\"responsive\"><\/figure><\/div><div class=\"tiled-gallery__col\" style=\"flex-basis:33.33333%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" role=\"button\" tabindex=\"0\" aria-label=\"Open image 8 of 14 in full-screen\" srcset=\"https:\/\/i2.wp.com\/mezquitadesevilla.com\/wp-content\/uploads\/2021\/07\/IMG_4689-scaled.jpeg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i2.wp.com\/mezquitadesevilla.com\/wp-content\/uploads\/2021\/07\/IMG_4689-scaled.jpeg?strip=info&#038;w=900&#038;ssl=1 900w,https:\/\/i2.wp.com\/mezquitadesevilla.com\/wp-content\/uploads\/2021\/07\/IMG_4689-scaled.jpeg?strip=info&#038;w=1200&#038;ssl=1 1200w,https:\/\/i2.wp.com\/mezquitadesevilla.com\/wp-content\/uploads\/2021\/07\/IMG_4689-scaled.jpeg?strip=info&#038;w=1500&#038;ssl=1 1500w,https:\/\/i2.wp.com\/mezquitadesevilla.com\/wp-content\/uploads\/2021\/07\/IMG_4689-scaled.jpeg?strip=info&#038;w=1800&#038;ssl=1 1800w,https:\/\/i2.wp.com\/mezquitadesevilla.com\/wp-content\/uploads\/2021\/07\/IMG_4689-scaled.jpeg?strip=info&#038;w=2000&#038;ssl=1 2000w\" alt=\"\" data-height=\"1920\" data-id=\"14809\" data-link=\"https:\/\/mezquitadesevilla.com\/distribucion-de-corderos-eid-al-adha-2\/img_4689\/\" data-url=\"https:\/\/mezquitadesevilla.com\/wp-content\/uploads\/2021\/07\/IMG_4689-scaled.jpeg\" data-width=\"2560\" src=\"https:\/\/i2.wp.com\/mezquitadesevilla.com\/wp-content\/uploads\/2021\/07\/IMG_4689-scaled.jpeg?ssl=1\" data-amp-layout=\"responsive\"><\/figure><\/div><div class=\"tiled-gallery__col\" style=\"flex-basis:33.33333%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" role=\"button\" tabindex=\"0\" aria-label=\"Open image 9 of 14 in full-screen\" srcset=\"https:\/\/i1.wp.com\/mezquitadesevilla.com\/wp-content\/uploads\/2021\/07\/IMG_4698-scaled.jpeg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i1.wp.com\/mezquitadesevilla.com\/wp-content\/uploads\/2021\/07\/IMG_4698-scaled.jpeg?strip=info&#038;w=900&#038;ssl=1 900w,https:\/\/i1.wp.com\/mezquitadesevilla.com\/wp-content\/uploads\/2021\/07\/IMG_4698-scaled.jpeg?strip=info&#038;w=1200&#038;ssl=1 1200w,https:\/\/i1.wp.com\/mezquitadesevilla.com\/wp-content\/uploads\/2021\/07\/IMG_4698-scaled.jpeg?strip=info&#038;w=1500&#038;ssl=1 1500w,https:\/\/i1.wp.com\/mezquitadesevilla.com\/wp-content\/uploads\/2021\/07\/IMG_4698-scaled.jpeg?strip=info&#038;w=1800&#038;ssl=1 1800w,https:\/\/i1.wp.com\/mezquitadesevilla.com\/wp-content\/uploads\/2021\/07\/IMG_4698-scaled.jpeg?strip=info&#038;w=2000&#038;ssl=1 2000w\" alt=\"\" data-height=\"1920\" data-id=\"14803\" data-link=\"https:\/\/mezquitadesevilla.com\/distribucion-de-corderos-eid-al-adha-2\/img_4698\/\" data-url=\"https:\/\/mezquitadesevilla.com\/wp-content\/uploads\/2021\/07\/IMG_4698-scaled.jpeg\" data-width=\"2560\" src=\"https:\/\/i1.wp.com\/mezquitadesevilla.com\/wp-content\/uploads\/2021\/07\/IMG_4698-scaled.jpeg?ssl=1\" data-amp-layout=\"responsive\"><\/figure><\/div><\/div><div class=\"tiled-gallery__row\"><div class=\"tiled-gallery__col\" style=\"flex-basis:50.00000%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" role=\"button\" tabindex=\"0\" aria-label=\"Open image 10 of 14 in full-screen\" srcset=\"https:\/\/i1.wp.com\/mezquitadesevilla.com\/wp-content\/uploads\/2021\/07\/2717571a-5f0a-4d37-8cd7-6bbbf6a8b6f7.jpg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i1.wp.com\/mezquitadesevilla.com\/wp-content\/uploads\/2021\/07\/2717571a-5f0a-4d37-8cd7-6bbbf6a8b6f7.jpg?strip=info&#038;w=900&#038;ssl=1 900w,https:\/\/i1.wp.com\/mezquitadesevilla.com\/wp-content\/uploads\/2021\/07\/2717571a-5f0a-4d37-8cd7-6bbbf6a8b6f7.jpg?strip=info&#038;w=1200&#038;ssl=1 1200w,https:\/\/i1.wp.com\/mezquitadesevilla.com\/wp-content\/uploads\/2021\/07\/2717571a-5f0a-4d37-8cd7-6bbbf6a8b6f7.jpg?strip=info&#038;w=1500&#038;ssl=1 1500w,https:\/\/i1.wp.com\/mezquitadesevilla.com\/wp-content\/uploads\/2021\/07\/2717571a-5f0a-4d37-8cd7-6bbbf6a8b6f7.jpg?strip=info&#038;w=1800&#038;ssl=1 1800w,https:\/\/i1.wp.com\/mezquitadesevilla.com\/wp-content\/uploads\/2021\/07\/2717571a-5f0a-4d37-8cd7-6bbbf6a8b6f7.jpg?strip=info&#038;w=2000&#038;ssl=1 2000w\" alt=\"\" data-height=\"1536\" data-id=\"14799\" data-link=\"https:\/\/mezquitadesevilla.com\/distribucion-de-corderos-eid-al-adha-2\/2717571a-5f0a-4d37-8cd7-6bbbf6a8b6f7\/\" data-url=\"https:\/\/mezquitadesevilla.com\/wp-content\/uploads\/2021\/07\/2717571a-5f0a-4d37-8cd7-6bbbf6a8b6f7.jpg\" data-width=\"2048\" src=\"https:\/\/i1.wp.com\/mezquitadesevilla.com\/wp-content\/uploads\/2021\/07\/2717571a-5f0a-4d37-8cd7-6bbbf6a8b6f7.jpg?ssl=1\" data-amp-layout=\"responsive\"><\/figure><\/div><div class=\"tiled-gallery__col\" style=\"flex-basis:50.00000%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" role=\"button\" tabindex=\"0\" aria-label=\"Open image 11 of 14 in full-screen\" srcset=\"https:\/\/i0.wp.com\/mezquitadesevilla.com\/wp-content\/uploads\/2021\/07\/c3a14a7e-0673-4483-a807-3ac1172945f0.jpg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i0.wp.com\/mezquitadesevilla.com\/wp-content\/uploads\/2021\/07\/c3a14a7e-0673-4483-a807-3ac1172945f0.jpg?strip=info&#038;w=900&#038;ssl=1 900w,https:\/\/i0.wp.com\/mezquitadesevilla.com\/wp-content\/uploads\/2021\/07\/c3a14a7e-0673-4483-a807-3ac1172945f0.jpg?strip=info&#038;w=1200&#038;ssl=1 1200w,https:\/\/i0.wp.com\/mezquitadesevilla.com\/wp-content\/uploads\/2021\/07\/c3a14a7e-0673-4483-a807-3ac1172945f0.jpg?strip=info&#038;w=1500&#038;ssl=1 1500w,https:\/\/i0.wp.com\/mezquitadesevilla.com\/wp-content\/uploads\/2021\/07\/c3a14a7e-0673-4483-a807-3ac1172945f0.jpg?strip=info&#038;w=1600&#038;ssl=1 1600w\" alt=\"\" data-height=\"1200\" data-id=\"14797\" data-link=\"https:\/\/mezquitadesevilla.com\/distribucion-de-corderos-eid-al-adha-2\/c3a14a7e-0673-4483-a807-3ac1172945f0\/\" data-url=\"https:\/\/mezquitadesevilla.com\/wp-content\/uploads\/2021\/07\/c3a14a7e-0673-4483-a807-3ac1172945f0.jpg\" data-width=\"1600\" src=\"https:\/\/i0.wp.com\/mezquitadesevilla.com\/wp-content\/uploads\/2021\/07\/c3a14a7e-0673-4483-a807-3ac1172945f0.jpg?ssl=1\" data-amp-layout=\"responsive\"><\/figure><\/div><\/div><div class=\"tiled-gallery__row\"><div class=\"tiled-gallery__col\" style=\"flex-basis:29.92179%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" role=\"button\" tabindex=\"0\" aria-label=\"Open image 12 of 14 in full-screen\" srcset=\"https:\/\/i0.wp.com\/mezquitadesevilla.com\/wp-content\/uploads\/2021\/07\/6f5672b3-94d3-4361-b42e-5bc079b6b427.jpg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i0.wp.com\/mezquitadesevilla.com\/wp-content\/uploads\/2021\/07\/6f5672b3-94d3-4361-b42e-5bc079b6b427.jpg?strip=info&#038;w=900&#038;ssl=1 900w,https:\/\/i0.wp.com\/mezquitadesevilla.com\/wp-content\/uploads\/2021\/07\/6f5672b3-94d3-4361-b42e-5bc079b6b427.jpg?strip=info&#038;w=1200&#038;ssl=1 1200w,https:\/\/i0.wp.com\/mezquitadesevilla.com\/wp-content\/uploads\/2021\/07\/6f5672b3-94d3-4361-b42e-5bc079b6b427.jpg?strip=info&#038;w=1500&#038;ssl=1 1500w,https:\/\/i0.wp.com\/mezquitadesevilla.com\/wp-content\/uploads\/2021\/07\/6f5672b3-94d3-4361-b42e-5bc079b6b427.jpg?strip=info&#038;w=1600&#038;ssl=1 1600w\" alt=\"\" data-height=\"1200\" data-id=\"14795\" data-link=\"https:\/\/mezquitadesevilla.com\/distribucion-de-corderos-eid-al-adha-2\/6f5672b3-94d3-4361-b42e-5bc079b6b427\/\" data-url=\"https:\/\/mezquitadesevilla.com\/wp-content\/uploads\/2021\/07\/6f5672b3-94d3-4361-b42e-5bc079b6b427.jpg\" data-width=\"1600\" src=\"https:\/\/i0.wp.com\/mezquitadesevilla.com\/wp-content\/uploads\/2021\/07\/6f5672b3-94d3-4361-b42e-5bc079b6b427.jpg?ssl=1\" data-amp-layout=\"responsive\"><\/figure><figure class=\"tiled-gallery__item\"><img decoding=\"async\" role=\"button\" tabindex=\"0\" aria-label=\"Open image 13 of 14 in full-screen\" srcset=\"https:\/\/i2.wp.com\/mezquitadesevilla.com\/wp-content\/uploads\/2021\/07\/8ab35a6b-a41f-4d5d-b4e8-d70203d693b2.jpg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i2.wp.com\/mezquitadesevilla.com\/wp-content\/uploads\/2021\/07\/8ab35a6b-a41f-4d5d-b4e8-d70203d693b2.jpg?strip=info&#038;w=827&#038;ssl=1 827w\" alt=\"\" data-height=\"827\" data-id=\"14791\" data-link=\"https:\/\/mezquitadesevilla.com\/distribucion-de-corderos-eid-al-adha-2\/8ab35a6b-a41f-4d5d-b4e8-d70203d693b2\/\" data-url=\"https:\/\/mezquitadesevilla.com\/wp-content\/uploads\/2021\/07\/8ab35a6b-a41f-4d5d-b4e8-d70203d693b2.jpg\" data-width=\"827\" src=\"https:\/\/i2.wp.com\/mezquitadesevilla.com\/wp-content\/uploads\/2021\/07\/8ab35a6b-a41f-4d5d-b4e8-d70203d693b2.jpg?ssl=1\" data-amp-layout=\"responsive\"><\/figure><\/div><div class=\"tiled-gallery__col\" style=\"flex-basis:70.07821%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" role=\"button\" tabindex=\"0\" aria-label=\"Open image 14 of 14 in full-screen\" srcset=\"https:\/\/i2.wp.com\/mezquitadesevilla.com\/wp-content\/uploads\/2021\/07\/2c7522b3-cc3a-4918-8ade-589a851651f5.jpg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i2.wp.com\/mezquitadesevilla.com\/wp-content\/uploads\/2021\/07\/2c7522b3-cc3a-4918-8ade-589a851651f5.jpg?strip=info&#038;w=900&#038;ssl=1 900w,https:\/\/i2.wp.com\/mezquitadesevilla.com\/wp-content\/uploads\/2021\/07\/2c7522b3-cc3a-4918-8ade-589a851651f5.jpg?strip=info&#038;w=1024&#038;ssl=1 1024w\" alt=\"\" data-height=\"768\" data-id=\"14793\" data-link=\"https:\/\/mezquitadesevilla.com\/distribucion-de-corderos-eid-al-adha-2\/2c7522b3-cc3a-4918-8ade-589a851651f5\/\" data-url=\"https:\/\/mezquitadesevilla.com\/wp-content\/uploads\/2021\/07\/2c7522b3-cc3a-4918-8ade-589a851651f5.jpg\" data-width=\"1024\" src=\"https:\/\/i2.wp.com\/mezquitadesevilla.com\/wp-content\/uploads\/2021\/07\/2c7522b3-cc3a-4918-8ade-589a851651f5.jpg?ssl=1\" data-amp-layout=\"responsive\"><\/figure><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>The Seville Mosque Foundation has had the honor of distributing 14 lambs among 56 families in Seville on the occasion of Eid al Adha. This assistance was made possible thanks to the Tirmidhi Foundation of Malaysia, and local contributions. Generosity is an essential part of Islam and one of the signs of those who have &hellip;<\/p>\n","protected":false},"author":1,"featured_media":14839,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[17],"tags":[],"class_list":["post-19848","post","type-post","status-publish","format-standard","has-post-thumbnail","","category-activities"],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/i0.wp.com\/mezquitadesevilla.com\/wp-content\/uploads\/2021\/07\/CBEID.jpg?fit=1375%2C688&ssl=1","_links":{"self":[{"href":"https:\/\/mezquitadesevilla.com\/en\/wp-json\/wp\/v2\/posts\/19848","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mezquitadesevilla.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mezquitadesevilla.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mezquitadesevilla.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mezquitadesevilla.com\/en\/wp-json\/wp\/v2\/comments?post=19848"}],"version-history":[{"count":1,"href":"https:\/\/mezquitadesevilla.com\/en\/wp-json\/wp\/v2\/posts\/19848\/revisions"}],"predecessor-version":[{"id":19851,"href":"https:\/\/mezquitadesevilla.com\/en\/wp-json\/wp\/v2\/posts\/19848\/revisions\/19851"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mezquitadesevilla.com\/en\/wp-json\/wp\/v2\/media\/14839"}],"wp:attachment":[{"href":"https:\/\/mezquitadesevilla.com\/en\/wp-json\/wp\/v2\/media?parent=19848"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mezquitadesevilla.com\/en\/wp-json\/wp\/v2\/categories?post=19848"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mezquitadesevilla.com\/en\/wp-json\/wp\/v2\/tags?post=19848"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}